{"id":2114,"date":"2025-02-26T16:08:33","date_gmt":"2025-02-26T16:08:33","guid":{"rendered":"https:\/\/spm-macchine.com\/?post_type=macchina&#038;p=2114"},"modified":"2026-04-27T10:45:50","modified_gmt":"2026-04-27T10:45:50","slug":"93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici","status":"publish","type":"macchina","link":"https:\/\/spm-macchine.com\/en\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/","title":{"rendered":"93XAVI | Avvolgi Bandelle"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Macchina automatica per avvolgere le bandelle ai filtri cilindrici.<\/p>\n","protected":false},"featured_media":2089,"parent":0,"template":"","meta":{"_acf_changed":false,"content-type":""},"categoria-macchine":[32,27,40],"class_list":["post-2114","macchina","type-macchina","status-publish","has-post-thumbnail","hentry","categoria-macchine-bordatrici","categoria-macchine-lavorazione-media-filtrante","categoria-macchine-tutte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>93XAVI | Avvolgi Bandelle - SPM<\/title>\n<meta name=\"description\" content=\"Macchina automatica per avvolgere le bandelle per la produzione di Filtro cilindrico con bandelle di rinforzo avvolte ed incollate sul diametro esterno\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"93XAVI | Avvolgi Bandelle - SPM\" \/>\n<meta property=\"og:description\" content=\"Macchina automatica per avvolgere le bandelle per la produzione di Filtro cilindrico con bandelle di rinforzo avvolte ed incollate sul diametro esterno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/\" \/>\n<meta property=\"og:site_name\" content=\"SPM\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T10:45:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spm-macchine.com\/wp-content\/uploads\/2025\/02\/93XAVI-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/\",\"url\":\"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/\",\"name\":\"93XAVI | Avvolgi Bandelle - SPM\",\"isPartOf\":{\"@id\":\"https:\/\/spm-macchine.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/spm-macchine.com\/wp-content\/uploads\/2025\/02\/93XAVI-1.jpg\",\"datePublished\":\"2025-02-26T16:08:33+00:00\",\"dateModified\":\"2026-04-27T10:45:50+00:00\",\"description\":\"Macchina automatica per avvolgere le bandelle per la produzione di Filtro cilindrico con bandelle di rinforzo avvolte ed incollate sul diametro esterno\",\"breadcrumb\":{\"@id\":\"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/#primaryimage\",\"url\":\"https:\/\/spm-macchine.com\/wp-content\/uploads\/2025\/02\/93XAVI-1.jpg\",\"contentUrl\":\"https:\/\/spm-macchine.com\/wp-content\/uploads\/2025\/02\/93XAVI-1.jpg\",\"width\":1500,\"height\":1500,\"caption\":\"SPM | BAND WINDER FOR CYLINDRICAL FILTERS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/spm-macchine.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Macchine\",\"item\":\"https:\/\/spm-macchine.com\/archivio-macchine\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"93XAVI | Avvolgi Bandelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/spm-macchine.com\/#website\",\"url\":\"https:\/\/spm-macchine.com\/\",\"name\":\"SPM\",\"description\":\"le nostre macchine per la vostra produzione\",\"publisher\":{\"@id\":\"https:\/\/spm-macchine.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/spm-macchine.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/spm-macchine.com\/#organization\",\"name\":\"SPM\",\"url\":\"https:\/\/spm-macchine.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/spm-macchine.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/spm-macchine.com\/wp-content\/uploads\/2024\/08\/logo-SPM.jpg\",\"contentUrl\":\"https:\/\/spm-macchine.com\/wp-content\/uploads\/2024\/08\/logo-SPM.jpg\",\"width\":390,\"height\":184,\"caption\":\"SPM\"},\"image\":{\"@id\":\"https:\/\/spm-macchine.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"93XAVI | Avvolgi Bandelle - SPM","description":"Macchina automatica per avvolgere le bandelle per la produzione di Filtro cilindrico con bandelle di rinforzo avvolte ed incollate sul diametro esterno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/","og_locale":"en_US","og_type":"article","og_title":"93XAVI | Avvolgi Bandelle - SPM","og_description":"Macchina automatica per avvolgere le bandelle per la produzione di Filtro cilindrico con bandelle di rinforzo avvolte ed incollate sul diametro esterno","og_url":"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/","og_site_name":"SPM","article_modified_time":"2026-04-27T10:45:50+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/spm-macchine.com\/wp-content\/uploads\/2025\/02\/93XAVI-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/","url":"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/","name":"93XAVI | Avvolgi Bandelle - SPM","isPartOf":{"@id":"https:\/\/spm-macchine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/#primaryimage"},"image":{"@id":"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/#primaryimage"},"thumbnailUrl":"https:\/\/spm-macchine.com\/wp-content\/uploads\/2025\/02\/93XAVI-1.jpg","datePublished":"2025-02-26T16:08:33+00:00","dateModified":"2026-04-27T10:45:50+00:00","description":"Macchina automatica per avvolgere le bandelle per la produzione di Filtro cilindrico con bandelle di rinforzo avvolte ed incollate sul diametro esterno","breadcrumb":{"@id":"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/#primaryimage","url":"https:\/\/spm-macchine.com\/wp-content\/uploads\/2025\/02\/93XAVI-1.jpg","contentUrl":"https:\/\/spm-macchine.com\/wp-content\/uploads\/2025\/02\/93XAVI-1.jpg","width":1500,"height":1500,"caption":"SPM | BAND WINDER FOR CYLINDRICAL FILTERS"},{"@type":"BreadcrumbList","@id":"https:\/\/spm-macchine.com\/macchina\/93xavi-macchina-automatica-avvolgere-bandelle-filtri-cilindrici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spm-macchine.com\/en\/"},{"@type":"ListItem","position":2,"name":"Macchine","item":"https:\/\/spm-macchine.com\/archivio-macchine\/"},{"@type":"ListItem","position":3,"name":"93XAVI | Avvolgi Bandelle"}]},{"@type":"WebSite","@id":"https:\/\/spm-macchine.com\/#website","url":"https:\/\/spm-macchine.com\/","name":"SPM","description":"le nostre macchine per la vostra produzione","publisher":{"@id":"https:\/\/spm-macchine.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spm-macchine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spm-macchine.com\/#organization","name":"SPM","url":"https:\/\/spm-macchine.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spm-macchine.com\/#\/schema\/logo\/image\/","url":"https:\/\/spm-macchine.com\/wp-content\/uploads\/2024\/08\/logo-SPM.jpg","contentUrl":"https:\/\/spm-macchine.com\/wp-content\/uploads\/2024\/08\/logo-SPM.jpg","width":390,"height":184,"caption":"SPM"},"image":{"@id":"https:\/\/spm-macchine.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/spm-macchine.com\/en\/wp-json\/wp\/v2\/macchina\/2114"}],"collection":[{"href":"https:\/\/spm-macchine.com\/en\/wp-json\/wp\/v2\/macchina"}],"about":[{"href":"https:\/\/spm-macchine.com\/en\/wp-json\/wp\/v2\/types\/macchina"}],"version-history":[{"count":6,"href":"https:\/\/spm-macchine.com\/en\/wp-json\/wp\/v2\/macchina\/2114\/revisions"}],"predecessor-version":[{"id":2598,"href":"https:\/\/spm-macchine.com\/en\/wp-json\/wp\/v2\/macchina\/2114\/revisions\/2598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spm-macchine.com\/en\/wp-json\/wp\/v2\/media\/2089"}],"wp:attachment":[{"href":"https:\/\/spm-macchine.com\/en\/wp-json\/wp\/v2\/media?parent=2114"}],"wp:term":[{"taxonomy":"categoria-macchine","embeddable":true,"href":"https:\/\/spm-macchine.com\/en\/wp-json\/wp\/v2\/categoria-macchine?post=2114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}